{"id":2941,"date":"2019-12-10T20:12:59","date_gmt":"2019-12-10T20:12:59","guid":{"rendered":"http:\/\/naaco.local\/home\/"},"modified":"2025-11-20T17:00:57","modified_gmt":"2025-11-20T17:00:57","slug":"home","status":"publish","type":"page","link":"https:\/\/naaco3d.com\/de\/","title":{"rendered":"Heim"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section id=\"hero-desktop\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_section backround-gradient vc_row-o-full-height\"><!-- Row Backgrounds --><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid desktop-on vc_custom_1763424322814 vc_row-o-full-height vc_row-o-columns-middle vc_row-o-content-middle vc_row-flex\"><div class=\"aboveall wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner vc_custom_1763425138795\"><div class=\"wpb_wrapper\"><div id=\"ultimate-heading-67886a98b03251d55\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-67886a98b03251d55 uvc-8322 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-67886a98b03251d55 h1'  data-responsive-json-new='{\"font-size\":\"desktop:62px;\",\"line-height\":\"desktop:64px;\"}' ><h1 style=\"--font-weight:theme;margin-bottom:30px;\">Transform your Game Development<\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n        <div class=\"modelViewerBlock\" data-attributes='{&quot;align&quot;:&quot;center&quot;,&quot;uniqueId&quot;:&quot;model3135&quot;,&quot;currentViewer&quot;:&quot;modelViewer&quot;,&quot;multiple&quot;:false,&quot;O3DVSettings&quot;:{&quot;isFullscreen&quot;:true,&quot;isPagination&quot;:false,&quot;isNavigation&quot;:false,&quot;camera&quot;:null,&quot;mouseControl&quot;:true},&quot;environmentImage&quot;:null,&quot;lazyLoad&quot;:false,&quot;loading&quot;:&quot;auto&quot;,&quot;autoplay&quot;:false,&quot;shadow&quot;:&quot;1&quot;,&quot;autoRotate&quot;:false,&quot;zoomLevel&quot;:null,&quot;zoom&quot;:false,&quot;isPagination&quot;:false,&quot;isNavigation&quot;:false,&quot;hotspotStyle&quot;:&quot;style-1&quot;,&quot;preload&quot;:&quot;auto&quot;,&quot;rotationPerSecond&quot;:&quot;30&quot;,&quot;mouseControl&quot;:true,&quot;lockXAxisRotation&quot;:false,&quot;lockYAxisRotation&quot;:false,&quot;fullscreen&quot;:true,&quot;zoomInOutBtn&quot;:false,&quot;cameraBtn&quot;:false,&quot;variant&quot;:false,&quot;loadingPercentage&quot;:false,&quot;progressBar&quot;:true,&quot;rotate&quot;:false,&quot;rotateAlongX&quot;:&quot;0&quot;,&quot;rotateAlongY&quot;:&quot;75&quot;,&quot;exposure&quot;:&quot;1&quot;,&quot;stylesheet&quot;:null,&quot;additional&quot;:{&quot;ID&quot;:&quot;&quot;,&quot;Class&quot;:&quot;&quot;,&quot;CSS&quot;:null},&quot;animation&quot;:false,&quot;woo&quot;:false,&quot;selectedAnimation&quot;:&quot;&quot;,&quot;placement&quot;:&quot;shortcode&quot;,&quot;styles&quot;:{&quot;width&quot;:&quot;100%&quot;,&quot;height&quot;:&quot;700px&quot;,&quot;bgColor&quot;:&quot;transparent&quot;,&quot;progressBarColor&quot;:null},&quot;model&quot;:{&quot;modelUrl&quot;:&quot;https:\\\/\\\/naaco3d.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/NeilArmstrong.glb&quot;,&quot;poster&quot;:&quot;&quot;},&quot;models&quot;:[]}'><\/div>\n\n\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner vc_custom_1763425147108\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b032520cf\" data-id=\"6a98b032520cf\" data-height=\"300\" data-height-mobile=\"0\" data-height-tab=\"\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"0\" style=\"clear:both;display:block;\"><\/div><div id=\"ultimate-heading-14416a98b032520ed\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-14416a98b032520ed uvc-6014 accent-border-color\" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-14416a98b032520ed .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"desktop:34px;tablet_portrait:30px;mobile:24px;\",\"line-height\":\"desktop:44px;tablet_portrait:40px;mobile:34px;\"}'  style=\"font-weight:normal;color:#ffffff;margin-bottom:30px;\">Meticulously crafted 3D assets designed specifically for the most popular game engines in the industry.<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><!-- Row Backgrounds --><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section id=\"hero-mobile\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_section backround-gradient vc_row-o-full-height vc_section-o-content-middle vc_section-flex\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b03252334\" data-id=\"6a98b03252334\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div class=\"ult-spacer spacer-6a98b0325233c\" data-id=\"6a98b0325233c\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div id=\"ultimate-heading-57066a98b0325234c\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-57066a98b0325234c uvc-6062  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-57066a98b0325234c h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;\">Transform your Game Development<\/h1><\/div><\/div><div class=\"ult-spacer spacer-6a98b0325236f\" data-id=\"6a98b0325236f\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeIn fadeIn p-large\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Meticulously crafted 3D assets designed specifically for the most popular game engines in the industry.<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b032524f6\" data-id=\"6a98b032524f6\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n        <div class=\"modelViewerBlock\" data-attributes='{&quot;align&quot;:&quot;center&quot;,&quot;uniqueId&quot;:&quot;model3135&quot;,&quot;currentViewer&quot;:&quot;modelViewer&quot;,&quot;multiple&quot;:false,&quot;O3DVSettings&quot;:{&quot;isFullscreen&quot;:true,&quot;isPagination&quot;:false,&quot;isNavigation&quot;:false,&quot;camera&quot;:null,&quot;mouseControl&quot;:true},&quot;environmentImage&quot;:null,&quot;lazyLoad&quot;:false,&quot;loading&quot;:&quot;auto&quot;,&quot;autoplay&quot;:false,&quot;shadow&quot;:&quot;1&quot;,&quot;autoRotate&quot;:false,&quot;zoomLevel&quot;:null,&quot;zoom&quot;:false,&quot;isPagination&quot;:false,&quot;isNavigation&quot;:false,&quot;hotspotStyle&quot;:&quot;style-1&quot;,&quot;preload&quot;:&quot;auto&quot;,&quot;rotationPerSecond&quot;:&quot;30&quot;,&quot;mouseControl&quot;:true,&quot;lockXAxisRotation&quot;:false,&quot;lockYAxisRotation&quot;:false,&quot;fullscreen&quot;:true,&quot;zoomInOutBtn&quot;:false,&quot;cameraBtn&quot;:false,&quot;variant&quot;:false,&quot;loadingPercentage&quot;:false,&quot;progressBar&quot;:true,&quot;rotate&quot;:false,&quot;rotateAlongX&quot;:&quot;0&quot;,&quot;rotateAlongY&quot;:&quot;75&quot;,&quot;exposure&quot;:&quot;1&quot;,&quot;stylesheet&quot;:null,&quot;additional&quot;:{&quot;ID&quot;:&quot;&quot;,&quot;Class&quot;:&quot;&quot;,&quot;CSS&quot;:null},&quot;animation&quot;:false,&quot;woo&quot;:false,&quot;selectedAnimation&quot;:&quot;&quot;,&quot;placement&quot;:&quot;shortcode&quot;,&quot;styles&quot;:{&quot;width&quot;:&quot;100%&quot;,&quot;height&quot;:&quot;700px&quot;,&quot;bgColor&quot;:&quot;transparent&quot;,&quot;progressBarColor&quot;:null},&quot;model&quot;:{&quot;modelUrl&quot;:&quot;https:\\\/\\\/naaco3d.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/NeilArmstrong.glb&quot;,&quot;poster&quot;:&quot;&quot;},&quot;models&quot;:[]}'><\/div>\n\n\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"ult-spacer spacer-6a98b03252586\" data-id=\"6a98b03252586\" data-height=\"64\" data-height-mobile=\"300\" data-height-tab=\"\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section id=\"whoweare\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-parallax=\"1.5\" data-vc-parallax-image=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/bg-01.png\" class=\"vc_section vc_custom_1763411386936 vc_section-has-fill vc_general vc_parallax vc_parallax-content-moving\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-12 vc_col-lg-offset-3 vc_col-lg-6 vc_col-md-offset-3 vc_col-md-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b032527d1\" data-id=\"6a98b032527d1\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div id=\"ultimate-heading-52426a98b032527e4\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-52426a98b032527e4 uvc-6225  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-52426a98b032527e4 h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;\">We believe that creativity thrives in collaboration<\/h1><\/div><\/div><div class=\"ult-spacer spacer-6a98b03252802\" data-id=\"6a98b03252802\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeIn fadeIn p-large\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>That\u2019s why we provide complete support on &#8216;how-to&#8217;s, guiding you through every step of using our assets effectively. No more frustration\u2014just clear instructions to help you create extraordinary experiences.<\/p>\n<p>We dedicate ourselves to bring the best 3D assets for the industry and we pride ourselves in going above and beyond our support for them.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"ult-spacer spacer-6a98b0325284e\" data-id=\"6a98b0325284e\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div class=\"ult-spacer spacer-6a98b03252853\" data-id=\"6a98b03252853\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section id=\"services\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_section vc_custom_1763658036722 vc_section-has-fill vc_section-o-content-middle vc_section-flex\"><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-left\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><iframe loading=\"lazy\" title=\"Hayley 90 seconds about fear. (Dir. Stian Smestad Music by Nils Frahm)\" src=\"https:\/\/player.vimeo.com\/video\/181907337?dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b03252e34\" data-id=\"6a98b03252e34\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_column-gap-25 vc_row-o-equal-height vc_row-flex\"><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ultimate-heading-1446a98b03252f44\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-1446a98b03252f44 uvc-5734  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-1446a98b03252f44 h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;\">Exceptional Detail Meets Smart Technology<\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  p-large\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Our 3D assets boast high technical detail and smart features, allowing for dynamic interactions in your games. This ensures not only visual appeal but also enhances gameplay mechanics\u2014keeping players engaged like never before.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b032530f6\" data-id=\"6a98b032530f6\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_column-gap-25 vc_row-o-equal-height vc_row-flex\"><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-3 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1762883221861\"><div class=\"wpb_wrapper\"><div class=\"aio-icon-component  vc_custom_1762883363794   style_2\"><div id=\"Info-box-wrap-6276\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#F6F7F8;font-size:35px;display:inline-block;\">\n\t<i class=\"fas fa-cube\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-6276 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><\/p>\n<h3>Asset Creation<\/h3>\n<p>Body Medium. Most fonts have a particular weight which corresponds to one of the numbers in Common weight name mapping.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-3 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1762884232109\"><div class=\"wpb_wrapper\"><div class=\"aio-icon-component  vc_custom_1762884238226   style_2\"><div id=\"Info-box-wrap-4248\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#F6F7F8;font-size:35px;display:inline-block;\">\n\t<i class=\"fas fa-mountain-sun\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-4248 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><\/p>\n<h3>Environments<\/h3>\n<p>Body Medium. Most fonts have a particular weight which corresponds to one of the numbers in Common weight name mapping.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-3 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1762884246068\"><div class=\"wpb_wrapper\"><div class=\"aio-icon-component  vc_custom_1762883828668   style_2\"><div id=\"Info-box-wrap-5072\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#F6F7F8;font-size:35px;display:inline-block;\">\n\t<i class=\"fas fa-arrows-to-dot\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-5072 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><\/p>\n<h3>Rigging<\/h3>\n<p>Body Medium. Most fonts have a particular weight which corresponds to one of the numbers in Common weight name mapping.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-3 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1762884253335\"><div class=\"wpb_wrapper\"><div class=\"aio-icon-component  vc_custom_1762884098006   style_2\"><div id=\"Info-box-wrap-6697\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#F6F7F8;font-size:35px;display:inline-block;\">\n\t<i class=\"dt-icon-the7-misc-006-1\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-6697 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><\/p>\n<h3>Asset Creation<\/h3>\n<p>Body Medium. Most fonts have a particular weight which corresponds to one of the numbers in Common weight name mapping.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b032534be\" data-id=\"6a98b032534be\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section id=\"portfolio\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_section vc_custom_1762887694360 vc_section-has-fill vc_section-o-content-middle vc_section-flex\"><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_row-no-padding vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-offset-3 vc_col-lg-6 vc_col-md-offset-3 vc_col-md-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b0325363c\" data-id=\"6a98b0325363c\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div id=\"ultimate-heading-91116a98b0325364e\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-91116a98b0325364e uvc-9721  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-91116a98b0325364e h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;color:#006B00;\">A Thriving Community of Artists<\/h1><\/div><\/div><div class=\"ult-spacer spacer-6a98b0325366a\" data-id=\"6a98b0325366a\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_row-no-padding vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">#page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.content-bg-on.gradient-overlap-layout-list .post-entry-content {\n  background: linear-gradient(to bottom,,) no-repeat 0px 150px;\n}\n#page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.content-bg-on.gradient-overlap-layout-list .no-img .post-entry-content {\n  padding: 0px 0px 0px 0px;\n}\n#page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.content-bg-on.gradient-overlap-layout-list .no-img .post-entry-content:before {\n  display: none;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .paginator {\n  margin-top: 50px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter {\n  margin-bottom: 15px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter a,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter a * {\n  color: #F6F7F8;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .paginator a,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .paginator a * {\n  color: #F6F7F8;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .paginator .button-load-more {\n  border-color: rgba(246,247,248,0.1);\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .paginator .button-load-more:hover {\n  border-color: rgba(246,247,248,0.21);\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670\n    .filter:not(.filter-bg-decoration):not(.filter-underline-decoration)\n    .filter-categories a:hover,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670\n    .filter:not(.filter-bg-decoration):not(.filter-underline-decoration)\n    .filter-categories a.act {\n  color: #000000;\n  background: none;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter-bg-decoration .filter-categories a:not(.act):hover {\n  color: #000000;\n  background: none;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter-bg-decoration .filter-categories a.act {\n  color: #fff;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter-bg-decoration .filter-categories a.act:after {\n  background: #000000;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter-underline-decoration .filter-categories a:after {\n  background: #000000;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .paginator:not(.paginator-more-button) a:after {\n  background: #000000;\n}\n#page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter-switch {\n  background: rgba(0,0,0,0.2);\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .filter-switch-toggle {\n  background: #000000;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670:not(.mode-masonry) article:first-of-type,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670:not(.mode-masonry) article.visible.first {\n  margin-top: 0;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.dividers-on:not(.mode-masonry) article {\n  margin-top: 0;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.dividers-on:not(.mode-masonry) article:first-of-type,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.dividers-on:not(.mode-masonry) article.visible.first {\n  margin-top: 0;\n  padding-top: 0;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.hover-scale article:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.gradient-overlay-layout-list article {\n  border-radius: 0px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-thumbnail-wrap {\n  padding: 0px 0px 0px 0px;\n  border-radius: 0px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-thumbnail-wrap *,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-thumbnail-rollover:after {\n  border-radius: 0px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.enable-bg-rollover .post-thumbnail-rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.bottom-overlap-layout-list.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container {\n  height: calc(100% - 100px);\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: 10px 5px 10px;\n}\n.content-rollover-layout-list:not(.content-align-center).portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a,\n.gradient-overlay-layout-list:not(.content-align-center).portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a {\n  margin: 10px 10px 10px 0;\n}\n.dt-icon-border-on.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a:before {\n  border-width: 0px;\n  border-style: solid;\n}\n.dt-icon-hover-border-on.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a:after {\n  border-width: 0px;\n  border-style: solid;\n}\n.dt-icon-bg-on.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a:before {\n  background: rgba(255,255,255,0.3);\n  -webkit-box-shadow: none;\n  box-shadow: none;\n}\n.dt-icon-hover-bg-on.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a:after {\n  background: rgba(255,255,255,0.5);\n  -webkit-box-shadow: none;\n  box-shadow: none;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a > span,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a > span:before {\n  font-size: 16px;\n  line-height: 44px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a:not(:hover) > span {\n  color: #ffffff;\n}\n.dt-icon-hover-off.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a > span,\n.dt-icon-hover-off.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a:hover > span {\n  color: #ffffff;\n}\n.dt-icon-hover-on.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-links-container a:hover > span {\n  color: #ffffff;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .entry-title,\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.owl-carousel .entry-title {\n  margin-bottom: 20px;\n  font-weight: bold;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .entry-meta {\n  margin-bottom: 20px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .portfolio-categories {\n  margin-bottom: 20px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .entry-excerpt {\n  margin-bottom: 5px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670:not(.centered-layout-list) .post-entry-content {\n  padding: 0px 0px 0px 0px;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670:not(.centered-layout-list):not(\n      .content-bg-on\n    ):not(.mode-list)\n    .no-img\n    .post-entry-content {\n  padding: 0;\n}\n.portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.gradient-overlay-layout-list .post-entry-content {\n  border-radius: 0px;\n}\n@media screen and (max-width: ) {\n  .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 article {\n    -webkit-flex-flow: column nowrap;\n    -moz-flex-flow: column nowrap;\n    -ms-flex-flow: column nowrap;\n    flex-flow: column nowrap;\n    margin-top: 20px;\n  }\n  .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.dividers-on article {\n    border: none;\n  }\n  .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.content-bg-on.centered-layout-list article {\n    padding: 0;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-thumbnail-wrap,\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-entry-content {\n    width: 100%;\n    margin: 0;\n    top: 0;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-thumbnail-wrap {\n    padding: 0;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-entry-content:after {\n    display: none;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .project-even .post-thumbnail-wrap,\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.centered-layout-list .post-thumbnail-wrap {\n    -webkit-order: 0;\n    -moz-order: 0;\n    -ms-flex-order: 0;\n    order: 0;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.centered-layout-list .post-entry-title-content {\n    -webkit-order: 1;\n    -moz-order: 1;\n    -ms-flex-order: 1;\n    order: 1;\n    width: 100%;\n    padding: 20px 20px 0;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670.centered-layout-list .post-entry-content {\n    -webkit-order: 2;\n    -moz-order: 2;\n    -ms-flex-order: 2;\n    order: 2;\n    padding-top: 0;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-entry-content {\n    padding: 20px;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .entry-title {\n    margin: 3px 0 5px;\n    font-size: 20px;\n    line-height: 26px;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .entry-meta {\n    margin: 5px 0 5px;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .entry-excerpt {\n    margin: 15px 0 0;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-details {\n    margin: 5px 0 10px;\n  }\n  #page .portfolio-shortcode.portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 .post-details.details-type-link {\n    margin-bottom: 2px;\n  }\n}<\/style><div class=\"portfolio-shortcode portfolio-masonry-shortcode-id-62d3188164c5ba4edb60218372d71670 mode-masonry gradient-overlap-layout-list jquery-filter content-align-center dt-icon-bg-on dt-icon-border-on dt-icon-hover-on dt-icon-hover-bg-off quick-scale-img meta-info-off enable-bg-rollover resize-by-browser-width  vc_custom_1763416649539 loading-effect-fade-in description-under-image \" data-padding=\"0px\" data-cur-page=\"1\" data-post-limit=\"10\" data-pagination-mode=\"load-more\" aria-live=\"assertive\" data-desktop-columns-num=\"3\" data-v-tablet-columns-num=\"2\" data-h-tablet-columns-num=\"3\" data-phone-columns-num=\"1\" data-width=\"0px\" data-columns=\"0\"><div class=\"iso-container\" ><div class=\"visible wf-cell iso-item\" data-post-id=\"3688\" data-date=\"2025-11-21T16:17:57+00:00\" data-name=\"Breakfast scene\"><article class=\"post visible post-3688 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-environment dt_portfolio_category-food-drink dt_portfolio_category-13 dt_portfolio_category-16\" data-name=\"Breakfast scene\" data-date=\"2025-11-21T16:17:57+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/breakfast-scene\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img fetchpriority=\"high\" decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20970&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-301-3-768x970.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-301-3-768x970.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-301-3.jpg 949w\" loading=\"eager\" style=\"--ratio: 768 \/ 970\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"970\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/breakfast-scene\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/breakfast-scene\/\" target=\"\" title=\"Breakfast scene\" rel=\"bookmark\">Breakfast scene<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"3686\" data-date=\"2025-11-21T16:13:04+00:00\" data-name=\"Coffee bag 2\"><article class=\"post visible post-3686 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-food-drink dt_portfolio_category-16\" data-name=\"Coffee bag 2\" data-date=\"2025-11-21T16:13:04+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/coffee-bag-2\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20768&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-109-768x768.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-109-768x768.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-109-1152x1152.jpg 1152w\" loading=\"eager\" style=\"--ratio: 768 \/ 768\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"768\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/coffee-bag-2\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/coffee-bag-2\/\" target=\"\" title=\"Coffee bag 2\" rel=\"bookmark\">Coffee bag 2<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"3684\" data-date=\"2025-11-21T16:11:08+00:00\" data-name=\"Coffee bag\"><article class=\"post visible post-3684 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-food-drink dt_portfolio_category-16\" data-name=\"Coffee bag\" data-date=\"2025-11-21T16:11:08+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/coffe-bag\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20512&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-102-2-768x512.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-102-2-768x512.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-102-2-1152x768.jpg 1152w\" loading=\"eager\" style=\"--ratio: 768 \/ 512\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"512\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/coffe-bag\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/coffe-bag\/\" target=\"\" title=\"Coffee bag\" rel=\"bookmark\">Coffee bag<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"3682\" data-date=\"2025-11-21T16:02:47+00:00\" data-name=\"Coffee cup\"><article class=\"post visible post-3682 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-food-drink dt_portfolio_category-16\" data-name=\"Coffee cup\" data-date=\"2025-11-21T16:02:47+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/coffee-cup\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20970&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-119-768x970.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-119-768x970.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-119.jpg 949w\" loading=\"eager\" style=\"--ratio: 768 \/ 970\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"970\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/coffee-cup\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/coffee-cup\/\" target=\"\" title=\"Coffee cup\" rel=\"bookmark\">Coffee cup<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"3680\" data-date=\"2025-11-21T15:55:19+00:00\" data-name=\"Wine Bottle\"><article class=\"post visible post-3680 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-buildings-architecture dt_portfolio_category-clothing-and-accesories dt_portfolio_category-food-drink dt_portfolio_category-14 dt_portfolio_category-40 dt_portfolio_category-16\" data-name=\"Wine Bottle\" data-date=\"2025-11-21T15:55:19+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/wine-bottle\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20603&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-201-768x603.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-201-768x603.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-201-1152x905.jpg 1152w\" loading=\"eager\" style=\"--ratio: 768 \/ 603\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"603\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/wine-bottle\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/wine-bottle\/\" target=\"\" title=\"Wine Bottle\" rel=\"bookmark\">Wine Bottle<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"3676\" data-date=\"2025-11-21T15:46:17+00:00\" data-name=\"Tablet\"><article class=\"post visible post-3676 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-electronics dt_portfolio_category-41\" data-name=\"Tablet\" data-date=\"2025-11-21T15:46:17+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/tablet\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20603&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-210-6-768x603.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-210-6-768x603.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-210-6-1152x905.jpg 1152w\" loading=\"eager\" style=\"--ratio: 768 \/ 603\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"603\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/tablet\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/tablet\/\" target=\"\" title=\"Tablet\" rel=\"bookmark\">Tablet<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"3674\" data-date=\"2025-11-21T15:43:31+00:00\" data-name=\"Books\"><article class=\"post visible post-3674 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-buildings-architecture dt_portfolio_category-clothing-and-accesories dt_portfolio_category-furniture dt_portfolio_category-nature dt_portfolio_category-14 dt_portfolio_category-40 dt_portfolio_category-38 dt_portfolio_category-39\" data-name=\"Books\" data-date=\"2025-11-21T15:43:31+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/books\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20970&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-305-768x970.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-305-768x970.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-305.jpg 949w\" loading=\"eager\" style=\"--ratio: 768 \/ 970\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"970\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/books\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/books\/\" target=\"\" title=\"Books\" rel=\"bookmark\">Books<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"3668\" data-date=\"2025-11-21T15:40:35+00:00\" data-name=\"Long Nose Truck\"><article class=\"post visible post-3668 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-characters-creatures dt_portfolio_category-environment dt_portfolio_category-15 dt_portfolio_category-13\" data-name=\"Long Nose Truck\" data-date=\"2025-11-21T15:40:35+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/long-nose-truck\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20970&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/7-p-096-768x970.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/7-p-096-768x970.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/7-p-096.jpg 949w\" loading=\"eager\" style=\"--ratio: 768 \/ 970\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"970\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/long-nose-truck\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/long-nose-truck\/\" target=\"\" title=\"Long Nose Truck\" rel=\"bookmark\">Long Nose Truck<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"770\" data-date=\"2019-12-29T20:32:22+00:00\" data-name=\"Camera model\"><article class=\"post visible post-770 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-buildings-architecture dt_portfolio_category-clothing-and-accesories dt_portfolio_category-14 dt_portfolio_category-40\" data-name=\"Camera model\" data-date=\"2019-12-29T20:32:22+00:00\">\n\n<div class=\"post-thumbnail-wrap rollover-active \">\n\t<div class=\"post-thumbnail\">\n\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/camera-model\/\" class=\"post-thumbnail-rollover layzr-bg\" target=\"\"  aria-label=\"Post image\"><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20768%20970&#39;%2F%3E\" data-src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-304-768x970.jpg\" data-srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-304-768x970.jpg 768w, https:\/\/naaco3d.com\/wp-content\/uploads\/2019\/12\/p-304.jpg 949w\" loading=\"eager\" style=\"--ratio: 768 \/ 970\" sizes=\"(max-width: 768px) 100vw, 768px\" alt=\"\"  width=\"768\" height=\"970\"  \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/naaco3d.com\/de\/project\/camera-model\/\" target=\"\" class=\"project-details\" aria-label=\"Details link\"><span class=\"icon-portfolio-p205\"><\/span><\/a><\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/naaco3d.com\/de\/project\/camera-model\/\" target=\"\" title=\"Camera model\" rel=\"bookmark\">Camera model<\/a>\n\t<\/h3>\n\n\t\n\t\n\t\n<\/div><\/article><\/div><\/div><!-- iso-container|iso-grid --><div class=\"paginator paginator-more-button\">\n\t\t\t\t<a class=\"button-load-more \" href=\"javascript:void(0);\" data-dt-page=\"1\" ><span class=\"stick\"><\/span><span class=\"stick\"><\/span><span class=\"stick\"><\/span><span class=\"button-caption\">Mehr laden<\/span><\/a>\n\t\t\t<\/div><\/div><div class=\"ult-spacer spacer-6a98b03256a35\" data-id=\"6a98b03256a35\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section id=\"partners\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_section vc_custom_1763418215947 vc_section-has-fill\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp wpb_column vc_column_container vc_col-sm-12 vc_col-lg-offset-3 vc_col-lg-6 vc_col-md-offset-3 vc_col-md-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ultimate-heading-51006a98b03256c94\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-51006a98b03256c94 uvc-3882  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-51006a98b03256c94 h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;color:#7821BE;\">Brands that trust our work<\/h1><\/div><\/div><div class=\"ult-spacer spacer-6a98b03256cb4\" data-id=\"6a98b03256cb4\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"82\" height=\"96\" src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/Epic_Games_logo.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Epic_Games_logo\"  data-dt-location=\"https:\/\/naaco3d.com\/de\/home\/epic_games_logo\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"181\" height=\"82\" src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/Devolver_Digital_logo.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Devolver_Digital_logo\"  data-dt-location=\"https:\/\/naaco3d.com\/de\/home\/devolver_digital_logo\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"172\" height=\"46\" src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/Team17_logo_2018.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Team17_logo_(2018)\"  data-dt-location=\"https:\/\/naaco3d.com\/de\/home\/team17_logo_2018\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"385\" height=\"77\" src=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/naughy-logo.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"naughy logo\" srcset=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/naughy-logo.png 385w, https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/naughy-logo-300x60.png 300w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\"  data-dt-location=\"https:\/\/naaco3d.com\/de\/home\/naughy-logo\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section id=\"contact\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-parallax=\"1.5\" data-vc-parallax-image=\"https:\/\/naaco3d.com\/wp-content\/uploads\/2025\/11\/bg-01.png\" class=\"vc_section vc_custom_1763418188990 vc_section-has-fill vc_general vc_parallax vc_parallax-content-moving\"><div class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_row-o-content-top vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-spacer spacer-6a98b03257642\" data-id=\"6a98b03257642\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div id=\"ultimate-heading-26676a98b03257657\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-26676a98b03257657 uvc-1552  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-26676a98b03257657 h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;\">Let\u2019s build it together<\/h1><\/div><\/div><div class=\"ult-spacer spacer-6a98b03257674\" data-id=\"6a98b03257674\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><\/p>\n<table class=\"wp-list-table widefat fixed striped table-view-list forms\">\n<tbody id=\"the-list\" data-wp-lists=\"list:form\">\n<tr>\n<td class=\"shortcode column-shortcode\" data-colname=\"Shortcode\">\n<style id=\"wpforms-css-vars-3293\">\n\t\t\t\t#wpforms-3293 {\n\t\t\t\t--wpforms-field-border-color: rgba(0, 0, 0, 0.25);\n--wpforms-field-border-color-spare: rgba(0, 0, 0, 0.25);\n--wpforms-field-text-color: rgba(0, 0, 0, 0.7);\n--wpforms-label-color: F6F7F8;\n--wpforms-label-sublabel-color: F6F7F8;\n--wpforms-label-error-color: CF95E7;\n--wpforms-button-border-size: px;\n--wpforms-button-border-radius: 10px;\n--wpforms-button-background-color: 7821BE;\n--wpforms-button-text-color: #f6f7f8;\n--wpforms-container-padding: 0px;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-radius: 3px;\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style>\n<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-3293\">\n<form id=\"wpforms-form-3293\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"3293\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/2941\" data-token=\"282e143f1a6ea1d3875f9c1a626b1828\" data-token-time=\"1788391474\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><\/p>\n<div id=\"wpforms-error-noscript\" style=\"display: none;\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/div>\n<div class=\"wpforms-field-container\">\n<div id=\"wpforms-3293-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t><br \/>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-3293-field_4\" >Name Email Message<\/label><br \/>\n\t\t\t<input type=\"text\" id=\"wpforms-3293-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n<div id=\"wpforms-3293-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\">\n<fieldset>\n<legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend>\n<div class=\"wpforms-field-row wpforms-field-medium\">\n<div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-3293-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-3293-field_1-error\" required><label for=\"wpforms-3293-field_1\" class=\"wpforms-field-sublabel after\">Vorname<\/label><\/div>\n<div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-3293-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-3293-field_1-last-error\" required><label for=\"wpforms-3293-field_1-last\" class=\"wpforms-field-sublabel after\">Nachname<\/label><\/div>\n<\/div>\n<\/fieldset>\n<\/div>\n<div id=\"wpforms-3293-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-3293-field_2\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3293-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-3293-field_2-error\" required><\/div>\n<div id=\"wpforms-3293-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-3293-field_3\">Message<\/label><textarea id=\"wpforms-3293-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-3293-field_3-error\" ><\/textarea><\/div>\n<p><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-3293-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-3293-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-3293-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div>\n<p><!-- .wpforms-field-container --><\/p>\n<div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"3293\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/pages\/2941\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3293\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naaco3d.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div>\n<\/form>\n<\/div>\n<p>  <!-- .wpforms-container --><\/td>\n<td class=\"created column-created\" data-colname=\"Date\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<\/div>\n\t\t<\/div><\/div><div class=\"ult-spacer spacer-6a98b0325847a\" data-id=\"6a98b0325847a\" data-height=\"64\" data-height-mobile=\"64\" data-height-tab=\"64\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Transform your Game Development Meticulously crafted 3D assets designed specifically for the most popular game engines in the industry.Transform your Game Development Meticulously crafted 3D assets designed specifically for the most popular game engines in the industry. We believe that creativity thrives in collaboration That\u2019s why we provide complete support on &#8216;how-to&#8217;s, guiding you through&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2941","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/pages\/2941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/comments?post=2941"}],"version-history":[{"count":20,"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/pages\/2941\/revisions"}],"predecessor-version":[{"id":3602,"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/pages\/2941\/revisions\/3602"}],"wp:attachment":[{"href":"https:\/\/naaco3d.com\/de\/wp-json\/wp\/v2\/media?parent=2941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}